{"id":22574,"date":"2025-09-04T08:05:47","date_gmt":"2025-09-04T08:05:47","guid":{"rendered":"https:\/\/euramobil-25.tiw-01.mxp.services\/?post_type=events&#038;p=22574"},"modified":"2026-03-31T08:09:41","modified_gmt":"2026-03-31T08:09:41","slug":"reisemobile-duelmen-herbstmesse-2025","status":"publish","type":"events","link":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/events\/reisemobile-duelmen-herbstmesse-2025\/","title":{"rendered":"Reisemobile D\u00fclmen Herbstmesse 2025"},"content":{"rendered":"<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>Am 20. und 21. September 2025 l\u00e4dt Reisemobile D\u00fclmen zur gro\u00dfen Herbstmesse mit Mobilvetta Treffen ein. Von 10:00 bis 18:00 Uhr dreht sich alles um unsere vielf\u00e4ltige Fahrzeugausstellung auf dem Hof \u2013 mit attraktiven Sonderangeboten, die nur w\u00e4hrend der Messe gelten. Eine perfekte Gelegenheit, Ihr Traum-Reisemobil zu entdecken und direkt von exklusiven Messe-Deals zu profitieren.<\/p>\n\n\n\n<p>Neben den Fahrzeugen erwartet die Besucher ein buntes Rahmenprogramm: Viele unserer bekannten Aussteller sind wieder dabei, erg\u00e4nzt durch spannende neue Partner. Auch f\u00fcr das leibliche Wohl ist gesorgt \u2013 mit Food Truck, Eiswagen und mehr.<\/p>\n\n\n\n<p>Und nat\u00fcrlich darf die allseits bekannte Camperparty nicht fehlen, die f\u00fcr beste Stimmung sorgt und die Messe zu einem echten Erlebnis macht.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Am 20. und 21. September 2025 l\u00e4dt Reisemobile D\u00fclmen zur gro\u00dfen Herbstmesse mit Mobilvetta Treffen ein. Von 10:00 bis 18:00 Uhr dreht sich alles um unsere vielf\u00e4ltige Fahrzeugausstellung auf dem Hof \u2013 mit attraktiven Sonderangeboten, die nur w\u00e4hrend der Messe gelten. Eine perfekte Gelegenheit, Ihr Traum-Reisemobil zu entdecken und direkt von exklusiven Messe-Deals zu profitieren. [&hellip;]<\/p>\n","protected":false},"featured_media":22570,"template":"","meta":{"_acf_changed":true,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"class_list":["post-22574","events","type-events","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/events\/22574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/types\/events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/media\/22570"}],"wp:attachment":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/media?parent=22574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}