{"id":13073,"date":"2022-08-23T07:12:08","date_gmt":"2022-08-23T07:12:08","guid":{"rendered":"https:\/\/euramobil-25.tiw-01.mxp.services\/?p=13073"},"modified":"2025-08-05T14:56:21","modified_gmt":"2025-08-05T14:56:21","slug":"profila-t-726-ef-qf-die-kroenung-der-profila-baureihe-in-einer-neuen-dimension","status":"publish","type":"post","link":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/profila-t-726-ef-qf-die-kroenung-der-profila-baureihe-in-einer-neuen-dimension\/","title":{"rendered":"Profila T 726 EF\/QF: Die Kr\u00f6nung der Profila Baureihe in einer neuen Dimension"},"content":{"rendered":"<p><strong>Zwei neue Grundrisse auf Mercedes Sprinter in der 7,50m Klasse \u25cf Face to Face Wohnraum \u25cf Raumb\u00e4der mit variablen Nutzungsm\u00f6glichkeiten \u25cf Komplettausstattung \u201eLuminary S\u201c veredelt Profila auf Mercedes zur Luxusklasse \u25cf gro\u00dfz\u00fcgiger Raumeindruck \u25cf 10 Jahre Dichtigkeitsgarantie<br><\/strong><\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Schon im Januar bei der Premiere der neuen Profila auf Mercedes in der 7m Klasse deutete sich eine neue Hierarchie in der Profila Palette an: Mercedes Sprinter Fahrgestell, AL-KO Tiefrahmen, ALDE-Warmwasserheizung und das aufstellbare Panorama-Glasdach positionieren die \u201eNeuen\u201c eine Klasse \u00fcber den vergleichbaren Modellen auf Fiat Ducato. Zur neuen Reisemobilsaison geht Eura Mobil diesen Weg konsequent weiter.<\/p>\n\n\n\n<p>Mit den 7,48m bzw. 7,61m langen Modellen Profila T 726 EF und 726 QF greift der Premium-Hersteller nun auch in der 7,50m Klasse arrivierte Mitbewerber der Luxusklasse an. Dazu passt, da\u00df Eura Mobil gleichzeitig seinen Luxus-Teilintegrierten Contura (ebenfalls auf Mercedes) k\u00fcnftig nur noch in der 8m Klasse anbietet.<\/p>\n\n\n\n<p>Aufbautechnisch und in Hinsicht auf das Basisfahrzeug nahezu identisch ausgestattet, schlie\u00dft Eura Mobil die L\u00fccke zum Contura in der 7,50m Klasse k\u00fcnftig zudem mit der Luxusausstattung \u201eLuminary S\u201c, die den Ausstattungsumfang der \u201eLuminary\u201c Pakete des Contura in einem Komplettpaket fast vollst\u00e4ndig auf den Profila T \u00fcbertr\u00e4gt.<\/p>\n\n\n\n<p>Doch auch die Grundrissgestaltung f\u00fchrt die Profila-Baureihe in eine neue Klasse: auf dem durchgehenden, 19,5cm hohen Doppelboden beeindrucken die Face to Face Wohnwelten mit viel Bewegungsfreiheit und toller Raumwirkung. Die sich in der Fahrzeugmitte anschlie\u00dfende K\u00fcche mit dynamisch geschwungener Front und gro\u00dfem K\u00fchlschrank inklusive klappbarer Arbeitsfl\u00e4chenerweiterung bildet gleichzeitig Zentrum wie auch die Verbindung zum Heckbereich. Das Raumbad mit Raumteilert\u00fcr zur K\u00fcche und Schiebet\u00fcren zum Schlafbereich fungiert dabei zum einen als separater Raum zum Duschen und Ankleiden und zum anderen als Erweiterung zum Schlafzimmer. Dort gl\u00e4nzt der Profila T 726 EF mit zwei je 2,03m langen Einzelbetten, w\u00e4hrend der 726 QF f\u00fcr die Freunde des Zentralbettes ein 1,95m langes und 1,47m breites Komfortbett mit H\u00f6henverstellung aufweisen kann. Gro\u00dfe Staur\u00e4ume im Heck verstehen sich in dieser Kombination aus Doppelboden und weitl\u00e4ufigem Heckabteil fast schon von selbst.<\/p>\n\n\n\n<p>Die neuen Grundrisse bestehen mit Hilfe des beheizten Doppelbodens zudem die Anforderungen der Winterfestigkeits-Norm EN 1646-1. Eine zehnj\u00e4hrige Garantie f\u00fcr Aufbaudichtigkeit und die dreij\u00e4hrige Garantie f\u00fcr den M\u00f6belbau belegen den Premium-Anspruch von Eura Mobil. Grundlage daf\u00fcr sind der moderne Aufbau aus geklebtem GFK-Verbundmaterial mit holzfreien W\u00e4nden und ein robuster M\u00f6belbau mit Aluminiumprofil-Verst\u00e4rkungen.<\/p>\n\n\n\n<p>Die Varianten \u201eMondial Edition\u201c bzw. \u201eLuminary S\u201c bilden aus der Kombination von mehreren Ausstattungspaketen einen attraktiven Gesamt-Preisvorteil. Die konkreten Preise der neuen Modelle werden zum Caravan Salon in D\u00fcsseldorf bekannt gegeben.<\/p>","protected":false},"excerpt":{"rendered":"<p>Zwei neue Grundrisse auf Mercedes Sprinter in der 7,50m Klasse \u25cf Face to Face Wohnraum \u25cf Raumb\u00e4der mit variablen Nutzungsm\u00f6glichkeiten \u25cf Komplettausstattung \u201eLuminary S\u201c veredelt Profila auf Mercedes zur Luxusklasse \u25cf gro\u00dfz\u00fcgiger Raumeindruck \u25cf 10 Jahre Dichtigkeitsgarantie<\/p>","protected":false},"author":1,"featured_media":13074,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[18,47,52],"tags":[],"class_list":["post-13073","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eura-mobil-news-2022","category-fr","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/posts\/13073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/comments?post=13073"}],"version-history":[{"count":2,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/posts\/13073\/revisions"}],"predecessor-version":[{"id":22376,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/posts\/13073\/revisions\/22376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/media\/13074"}],"wp:attachment":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/media?parent=13073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/categories?post=13073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/tags?post=13073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}