{"id":4667,"date":"2019-10-30T07:32:16","date_gmt":"2019-10-30T07:32:16","guid":{"rendered":"https:\/\/euramobil-25.tiw-01.mxp.services\/der-neue-contura-die-neue-oberklasse-zeigt-jetzt-auch-bei-den-teilintegrierten-flagge-copy\/"},"modified":"2025-08-05T15:03:46","modified_gmt":"2025-08-05T15:03:46","slug":"der-neue-contura-die-neue-oberklasse-zeigt-jetzt-auch-bei-den-teilintegrierten-flagge","status":"publish","type":"post","link":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/der-neue-contura-die-neue-oberklasse-zeigt-jetzt-auch-bei-den-teilintegrierten-flagge\/","title":{"rendered":"Der neue Contura: Die neue Oberklasse zeigt jetzt auch bei den Teilintegrierten Flagge"},"content":{"rendered":"<p><em>Luxuri\u00f6ser &nbsp;neuer Teilintegrierter \u25cf dynamisch markantes Design \u25cf Neuartiges Starlight Dome Panoramaglasdach mit Smartlift und Softclose Funktionalit\u00e4t \u25cf exklusive Detaill\u00f6sungen \u25cf Hochwertige Ausstattung f\u00fcr das Verreisen zu jeder Jahreszeit &nbsp;\u25cf Von Beginn an 10 Jahre Dichtigkeitsgarantie<\/em><\/p>\n\n\n\n<p>Mit dem neuen <strong><a href=\"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wohnmobile\/contura\/\">Contura<\/a><\/strong> zeigt Eura Mobil ab Saison 2020 Flagge bei den Teilintegrierten der Luxusklasse. Vor dem Hintergrund neu gewonnener St\u00e4rke bei den Integrierten zielt der Sprendlinger Hersteller jetzt auch auf besonders anspruchsvolle Kundschaft unter den Interessenten der kompakten Aufbauform.<\/p>\n\n\n\n<p>In Gestalt eines automotiven Designs mit markanten Lichtkanten und flacher Anbindung zwischen Fahrerhaus und modernem GFK-Aufbau betont der Contura vom Start weg den hohen Anspruch seiner Konstrukteure.<\/p>\n\n\n\n<p>Der mit einen ALKO-Tiefrahmenfahrgestell verbundene Contura \u00a0tr\u00e4gt einen besonders verwindungsfesten, langlebigen Aufbau, der mit Warmwasserheizung und stauraumoptimierten Doppelboden zu Reisen von beliebiger Dauer in jeder Jahreszeit einl\u00e4dt. \u00a0Sorgf\u00e4ltige Detailarbeit wird dabei nicht nur im Exterieur sondern auch innen sichtbar: der optisch\u00a0flie\u00dfende \u00dcbergang der Oberschr\u00e4nke vom Wohnraum in das Fahrerhaus wird an der Decke vom zweiteiligen \u201eStarlight Dome\u201c Panoramaglasdach begleitet, das exklusiv bei Eura Mobil zum Einsatz kommt. Das Frontelement ist in der Dachanbindung im Fahrerhaus als festes Glasdach integriert, w\u00e4hrend das zweite Dachfenster als Hebedach mittels 20% mehr Fl\u00e4che als herk\u00f6mmliche Hebekippd\u00e4cher f\u00fcr reichlich Frischluft und taghelle Atmosph\u00e4re im Vorderwagen sorgt. \u00d6ffnen und Schlie\u00dfen geht dabei ganz einfach: Dank Gasdruckd\u00e4mpfern mit Smart Lift Funktion l\u00e4sst sich die Acrylglashaube mit einem Finger in die gew\u00fcnschte Position anheben. Beim Schlie\u00dfen regelt ein Drehventil mit Soft Close Funktion sanft und stufenlos das Absenken in jeden gew\u00fcnschten \u00d6ffnungswinkel bis in die Grundstellung. Eine besondere Faszination strahlt das gro\u00dfe, zweiteilige Dachfenster abends unter sternenklarem Himmelszelt aus. Das geradezu nach oben \u201eoffene\u201c Raumgef\u00fchl entwickelt dabei einen ganz eigenen, un\u00fcbertroffen gro\u00dfz\u00fcgigen Charme. Die dimmbare Ambientebeleuchtung liefert die individuell dazu passende Lichtstimmung im\u00a0Innenraum.<\/p>\n\n\n\n<p>Der Wohnraum im Contura ist auch abseits von Sternenhimmelromantik von einem Ineinander von atmosph\u00e4rischem Wohlf\u00fchlambiente&nbsp;und ganz praktischen Eigenschaften gepr\u00e4gt. Dabei orientiert sich der Contura bei den M\u00f6beln und der Ausstattung am 2017 vorgestellten Luxus-Integrierten Integra.<\/p>\n\n\n\n<p>Der neue Contura profitiert von einer exklusiv f\u00fcr die Luxusklasse entwickelten M\u00f6belarchitektur. Edles Wohlf\u00fchlambiente\u00a0durch hochwertige Materialien und erstklassige Verarbeitung bilden die Basis f\u00fcr stilvolles Verreisen. Hochgl\u00e4nzende Oberschr\u00e4nke in Edelholzoptik mit breiten Chromeinlegern zeigen schon auf den ersten Blick den Oberklasse-Anspruch des Contura. \u00dcppiger Einsatz von Chrom-Elementen findet sich auch bei den Unterschr\u00e4nken, den Bettverblendungen an der R\u00fcckwand und in vielen weiteren Details. Im optisch reizvollen Kontrast dazu stehen die sonst matten Oberfl\u00e4chen des M\u00f6belkorpus sowie die in hellem Creme-T\u00f6nen gehaltenen Arbeitsfl\u00e4chen, M\u00f6belwangen und Wandelemente.<\/p>\n\n\n\n<p>Im Wohnraum dominieren je nach Grundriss zwei luxuri\u00f6se L\u00e4ngssofa oder eine klassische L-Sitzgruppe mit flauschigen Kissen statt klassischer R\u00fcckenpolster den Lounge-Charakter des Contura. Eine beheizbare Windschutzscheibe und ein Sound-System geh\u00f6ren zu den weiteren Upgrade-M\u00f6glichkeiten, w\u00e4hrend Zentralverriegelung und Spiegel mit elektrischer Verstellung und Weitwinkelfeld bereits in der Serienausstattung enthalten sind.<\/p>\n\n\n\n<p>In der K\u00fcche freuen sich die Reisenden \u00fcber einen ergonomisch geschwungenen K\u00fcchenblock mit gro\u00dfem K\u00fchlschrank und den schwenkbaren Federarm-Wasserhahn. Als stilvolles und praktisches Detail zeigt sich die Glas-Vitrine im Oberschrank.<\/p>\n\n\n\n<p>Der Waschraum wird von der Lichtstimmung der hinterleuchteten Duschs\u00e4ule gepr\u00e4gt, die wie die Badt\u00fcr mit einer Schilfgrasintarsie f\u00fcr ein entspanntes Ambiente sorgt. Auch im Schlafbereich ist das Wohlf\u00fchlambiente zentraler Ansatzpunkt f\u00fcr die Gestaltung. Die edle R\u00fcckwandverblendung mit indirekt beleuchteten Chromelementen und die zur Fahrzeugmitte konkav geformten Oberschr\u00e4nke gehen an der Decke in flache, beleuchtete Baldachine \u00fcber, die bis zur Verbindungst\u00fcr durchgezogen sind. Je nach Grundriss bieten die Schlafr\u00e4ume entweder zwei gro\u00dfe Einzelbetten mit bis zu 2,00m L\u00e4nge (Contura 710 EB und 760 EB) oder ein h\u00f6henverstellbares gro\u00dfz\u00fcgiges Zentralbett f\u00fcr erstklassigen Schlafkomfort (Contura 760 QB und 760 QF) . Unter den Betten halten bis zu 1,24 m hohe Garagen jede Menge Stauraumvolumen bereit.<\/p>\n\n\n\n<p>Der f\u00fcr Eura Mobil typische, durchgehende beheizte Doppelboden beherbergt alle technischen Installationen im frostsicheren Keller des Mobils und bietet weitere, vom Innenraum zug\u00e4ngliche Staum\u00f6glichkeiten. Ein zentrales Technikfach erm\u00f6glicht von au\u00dfen den Zugriff auf Wasserablassh\u00e4hne und den zentralen Elektroverteiler. Die auf Wunsch erh\u00e4ltliche, per Knopfdruck vom Fahrersitz bet\u00e4tigte Abwassertankentleerung per Monitorkontrolle und Kameraf\u00fchrung optimiert den Bedienkomfort. Neu im Doppelbodenkonzept von Eura Mobil sind die zus\u00e4tzlichen, abgesenkten Boden- und Seiten-Stauf\u00e4cher mit 30 cm H\u00f6he.<\/p>\n\n\n\n<p>Der Oberklasse-Anspruch zeigt sich auch in der zehnj\u00e4hrigen Garantie f\u00fcr Aufbaudichtigkeit und in der dreij\u00e4hrigen Garantie f\u00fcr den M\u00f6belbau. R\u00fcckgrat daf\u00fcr sind der modern Aufbau aus geklebtem GFK-Verbundmaterial mit holzfreien W\u00e4nden und ein robuster M\u00f6belbau mit Aluminiumprofil-Verst\u00e4rkungen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Luxuri\u00f6ser &nbsp;neuer Teilintegrierter \u25cf dynamisch markantes Design \u25cf Neuartiges Starlight Dome Panoramaglasdach mit Smartlift und Softclose Funktionalit\u00e4t \u25cf exklusive Detaill\u00f6sungen \u25cf Hochwertige Ausstattung f\u00fcr das Verreisen zu jeder Jahreszeit &nbsp;\u25cf Von Beginn an 10 Jahre Dichtigkeitsgarantie Mit dem neuen Contura zeigt Eura Mobil ab Saison 2020 Flagge bei den Teilintegrierten der Luxusklasse. Vor dem Hintergrund [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5234,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[11,47,52],"tags":[],"class_list":["post-4667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11","category-fr","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/posts\/4667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/comments?post=4667"}],"version-history":[{"count":5,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/posts\/4667\/revisions"}],"predecessor-version":[{"id":22401,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/posts\/4667\/revisions\/22401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/media\/5234"}],"wp:attachment":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/media?parent=4667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/categories?post=4667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/de_at\/wp-json\/wp\/v2\/tags?post=4667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}