{"id":311,"date":"2019-04-01T11:56:30","date_gmt":"2019-04-01T11:56:30","guid":{"rendered":"https:\/\/euramobil-25.tiw-01.mxp.services\/?p=305"},"modified":"2025-08-05T15:05:10","modified_gmt":"2025-08-05T15:05:10","slug":"qui-possede-le-plus-ancien-vehicule-eura-mobil-encore-en-etat-de-marche","status":"publish","type":"post","link":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wer-besitzt-das-aelteste-noch-fahrtuechtige-eura-mobil-fahrzeug\/","title":{"rendered":"Qui poss\u00e8de le plus ancien v\u00e9hicule Eura-Mobil encore en \u00e9tat de marche ?"},"content":{"rendered":"<p><em>En 2019, Eura Mobil f\u00eatera ses 60 ans d'existence. Pour cet anniversaire, Eura Mobil recherche des v\u00e9hicules de loisirs historiques et encore en \u00e9tat de marche ou de traction de sa propre production.<\/em><\/p>\n\n\n\n<p>Eura Mobil s'int\u00e9resse particuli\u00e8rement \u00e0 <strong>Caravanes Blessing et Eura<\/strong> des ann\u00e9es soixante-dix ainsi que des camping-cars de la premi\u00e8re moiti\u00e9 des ann\u00e9es quatre-vingt. La recherche de caravanes datant des ann\u00e9es de fondation \u00e0 partir de 1969 s'av\u00e8re difficile - mais les camping-cars des trois premi\u00e8res ann\u00e9es de production, de 1983 \u00e0 1986, sont \u00e9galement rares. Apr\u00e8s la destruction de son propre camping-car historique Eura de 1983 lors de l'incendie de la salle d'exposition en 2014, l'usine de Sprendlingen esp\u00e8re obtenir de l'aide.<\/p>\n\n\n\n<p>Lors du Caravan Salon de D\u00fcsseldorf de cette ann\u00e9e, Eura Mobil pr\u00e9voit de pr\u00e9senter ses deux plus anciens v\u00e9hicules de loisirs. En outre, les v\u00e9hicules seront expos\u00e9s lors de l'ouverture du nouveau Reisemobil Forum au printemps 2020. Les propri\u00e9taires de v\u00e9hicules historiques Eura Mobil qui souhaitent participer \u00e0 ce concours peuvent s'adresser par e-mail \u00e0 <a href=\"mailto:info@euramobil-25.tiw-01.mxp.services\">info@euramobil-25.tiw-01.mxp.services<\/a>.<\/p>\n\n\n\n<p>Le propri\u00e9taire du plus ancien Eura Mobil recevra en remerciement une semaine de vacances dans un Eura Mobil Integra Line flambant neuf.<\/p>","protected":false},"excerpt":{"rendered":"<p>2019 feiert Eura Mobil sein 60-j\u00e4hriges Bestehen. F\u00fcr das Jubil\u00e4um sucht Eura Mobil historische und noch fahrbereite oder zugf\u00e4hige Freizeitfahrzeuge aus eigener Produktion. Besonderes Interesse zeigt Eura Mobil an Blessing- und Eura-Caravans aus den Siebzigern sowie an Reisemobilen aus der ersten H\u00e4lfte der achtziger Jahre. Als schwierig erweist sich die Suche nach Wohnwagen aus den [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5258,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[11,53],"tags":[],"class_list":["post-311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11","category-aktion"],"acf":[],"_links":{"self":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/posts\/311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/comments?post=311"}],"version-history":[{"count":2,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/posts\/311\/revisions"}],"predecessor-version":[{"id":22407,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/posts\/311\/revisions\/22407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/media\/5258"}],"wp:attachment":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/media?parent=311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/categories?post=311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/tags?post=311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}