{"id":5992,"date":"2019-10-30T07:28:48","date_gmt":"2019-10-30T07:28:48","guid":{"rendered":"https:\/\/euramobil-25.tiw-01.mxp.services\/?p=5992"},"modified":"2025-08-05T15:04:02","modified_gmt":"2025-08-05T15:04:02","slug":"integra-line-650-hs-integre-compact-et-confortable-avec-un-espace-genereux","status":"publish","type":"post","link":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/integra-line-650-hs-kompakter-und-komfortabler-integrierter-mit-grosszuegigem-raumangebot\/","title":{"rendered":"Integra Line 650 HS : Int\u00e9grable compact et confortable avec un espace g\u00e9n\u00e9reux"},"content":{"rendered":"<p><em>Acc\u00e8s \u00e0 la classe 6,50m \u25cf D\u00eenette arri\u00e8re spacieuse \u25cf Double plancher chauff\u00e9 avec beaucoup d'espace de rangement \u25cf Grande cuisine avec r\u00e9frig\u00e9rateur de 140 litres \u25cf Troisi\u00e8me et quatri\u00e8me places \u00e0 l'arri\u00e8re sans affecter l'espace de rangement \u25cf Garantie d'\u00e9tanch\u00e9it\u00e9 de 10 ans \u25cf<\/em><\/p>\n\n\n\n<p>A l'occasion de son 60\u00e8me anniversaire, Eura Mobil se lance dans la cat\u00e9gorie des int\u00e9graux compacts de 6,50m. Le nouvel Integra Line 650 HS convainc par son espace g\u00e9n\u00e9reux, tant dans le v\u00e9hicule lui-m\u00eame que dans le double plancher chauff\u00e9. D\u00e8s l'entr\u00e9e, l'IL 650 HS donne une belle impression d'espace gr\u00e2ce \u00e0 son axe visuel ouvert. Les faits le prouvent : deux banquettes longitudinales de 2,20 m et 1,43 m sont regroup\u00e9es autour de la banquette transversale de 2,17 m de large \u00e0 l'arri\u00e8re, ce qui permet d'accueillir jusqu'\u00e0 5 personnes en toute convivialit\u00e9. En dessous, un vaste espace de rangement s'\u00e9tend dans le double plancher chauff\u00e9. L'ancrage du cadre de ceinture dans des profil\u00e9s en aluminium sur les parois int\u00e9rieures est unique dans le secteur. Ainsi, le volume de rangement sous les banquettes est enti\u00e8rement pr\u00e9serv\u00e9, m\u00eame lors de l'installation de la troisi\u00e8me et de la quatri\u00e8me place de ceinture. Gr\u00e2ce \u00e0 trois grands abattants de rangement, les voyageurs ont toujours un acc\u00e8s optimal \u00e0 leurs bagages de chaque c\u00f4t\u00e9.<\/p>\n\n\n\n<p>Devant la d\u00eenette arri\u00e8re s'\u00e9tend un bloc-cuisine aux courbes ergonomiques avec, sur le c\u00f4t\u00e9 oppos\u00e9, un r\u00e9frig\u00e9rateur de 140 litres \u00e0 hauteur de plafond. Au milieu du v\u00e9hicule, on trouve un cabinet de toilette moderne de seulement 114 cm de long, avec lavabo pivotant et cabine de douche int\u00e9gr\u00e9e. Le lit escamotable, qui s'abaisse tr\u00e8s loin, se termine c\u00f4t\u00e9 conducteur par une armoire \u00e0 mi-hauteur.<\/p>\n\n\n\n<p>Tous les mod\u00e8les Integra Line r\u00e9pondent \u00e9galement aux exigences de la norme EN 1646-1 en mati\u00e8re de r\u00e9sistance aux conditions hivernales gr\u00e2ce au double plancher chauffant. Ainsi, marcher pieds nus en hiver devient rapidement un privil\u00e8ge quotidien dans l\u2019Integra Line.<\/p>\n\n\n\n<p>Une garantie de dix ans sur l\u2019\u00e9tanch\u00e9it\u00e9 de la carrosserie et une garantie de trois ans sur la fabrication du mobilier d\u00e9montrent l\u2019ambition d\u2019Eura Mobil en mati\u00e8re de qualit\u00e9 haut de gamme. Tout cela repose sur une construction moderne en mat\u00e9riau composite \u00e0 base de fibres de verre coll\u00e9 avec des parois sans bois et une construction de meubles robuste avec des renforcements en profil\u00e9s aluminium.<\/p>","protected":false},"excerpt":{"rendered":"<p>Einstieg in die 6,50m Klasse \u25cf ger\u00e4umige Hecksitzgruppe \u25cf beheizter Doppelboden mit viel Stauraum \u25cf Gro\u00dfe K\u00fcche mit 140 Liter K\u00fchlschrank \u25cf Dritter und vierter Sitzplatz im Heck ohne Beeintr\u00e4chtigung des Stauraumangebots &nbsp;\u25cf 10 Jahre Dichtigkeitsgarantie \u25cf Zum 60 j\u00e4hrigen Jubil\u00e4um steigt Eura Mobil bei den Integrierten in die kompakte 6,50m Klasse ein. Der neue [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5986,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[11,47,52],"tags":[],"class_list":["post-5992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11","category-fr","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/posts\/5992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/comments?post=5992"}],"version-history":[{"count":2,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/posts\/5992\/revisions"}],"predecessor-version":[{"id":22402,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/posts\/5992\/revisions\/22402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/media\/5986"}],"wp:attachment":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/media?parent=5992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/categories?post=5992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/fr\/wp-json\/wp\/v2\/tags?post=5992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}