{"id":22452,"date":"2025-08-19T12:53:18","date_gmt":"2025-08-19T12:53:18","guid":{"rendered":"https:\/\/euramobil-25.tiw-01.mxp.services\/?post_type=events&#038;p=22452"},"modified":"2026-03-31T08:09:58","modified_gmt":"2026-03-31T08:09:58","slug":"fiera-autunnale-doerr-2025","status":"publish","type":"events","link":"https:\/\/euramobil-25.tiw-01.mxp.services\/it\/events\/doerr-herbstmesse-2025\/","title":{"rendered":"Fiera d'autunno di D\u00f6rr 2025"},"content":{"rendered":"<p>Il 27 e 28 settembre 2025, presso la sede dell'azienda a Bliesen nel Saarland, si terr\u00e0 la Fiera d'Autunno D\u00f6rr - l'ingresso \u00e8 gratuito. I visitatori possono aspettarsi un'ampia selezione di camper, camper, accessori e tecnologia.<br>Che siate appassionati di campeggio, curiosi o famiglie in cerca di ispirazione per la vostra prossima vacanza, al D\u00f6rr di Bliesen ce n'\u00e8 per tutti i gusti. Scoprite le offerte attuali e le promozioni speciali per i nostri camper e date un'occhiata alla nostra flotta a noleggio. I consulenti specializzati di Reisemobile D\u00f6rr saranno lieti di rispondere alle vostre domande e di fornirvi una consulenza personalizzata in entrambe le giornate.<\/p>","protected":false},"excerpt":{"rendered":"<p>Am 27. und 28. September 2025 findet die D\u00f6rr Herbstmesse auf dem Betriebsgel\u00e4nde in Bliesen im Saarland statt \u2013 der Eintritt ist frei. Besucherinnen und Besucher erwartet eine gro\u00dfe Auswahl an Reisemobilen, Campervans, Zubeh\u00f6r und Technik.Ob Camping-Enthusiast, neugieriger Einsteiger oder Familie auf der Suche nach Inspiration f\u00fcr den n\u00e4chsten Urlaub \u2013 bei D\u00f6rr in Bliesen [&hellip;]<\/p>\n","protected":false},"featured_media":22456,"template":"","meta":{"_acf_changed":true,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"class_list":["post-22452","events","type-events","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/it\/wp-json\/wp\/v2\/events\/22452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/it\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/it\/wp-json\/wp\/v2\/types\/events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/it\/wp-json\/wp\/v2\/media\/22456"}],"wp:attachment":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/it\/wp-json\/wp\/v2\/media?parent=22452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}