{"id":22810,"date":"2026-02-12T14:47:05","date_gmt":"2026-02-12T14:47:05","guid":{"rendered":"https:\/\/euramobil-25.tiw-01.mxp.services\/?post_type=events&#038;p=22810"},"modified":"2026-03-31T08:08:23","modified_gmt":"2026-03-31T08:08:23","slug":"festa-di-primavera-al-wohnmobile-ratzeburg","status":"publish","type":"events","link":"https:\/\/euramobil-25.tiw-01.mxp.services\/it\/events\/fruehlingsfest-bei-wohnmobile-ratzeburg\/","title":{"rendered":"Festa di primavera alla WOHNMOBILE RATZEBURG"},"content":{"rendered":"<p>Festa di primavera al WOHNMOBILE RATZEBURG - inizio della stagione 2026<\/p>\n\n\n\n<p>\ud83d\udcc5 14 e 15 marzo 2026<br>\u23f0 10-16 h<br>\ud83d\udccd An der Tongrube 4-6, 23909 Ratzeburg<\/p>\n\n\n\n<p>WOHNMOBILE RATZEBURG (AL-CAR Technology) vi invita alla festa di primavera all'inizio della stagione di campeggio 2026. I visitatori possono aspettarsi una delle pi\u00f9 grandi esposizioni di camper della regione, con circa 200 veicoli.<\/p>\n\n\n\n<p>\ud83d\udd39 Ampia selezione di camper e roulotte<br>\ud83d\udd39 Fino a 40% di sconto su veicoli selezionati<br>\ud83d\udd39 2026 nuovi modelli con planimetrie innovative<br>\ud83d\udd39 Noleggio camper con sconto fiera interna<br>\ud83d\udd39 In diretta: la presentatrice Melli con il camper \u201eCalli\u201c di CARAVAN.fm<\/p>\n\n\n\n<p>\ud83c\udf74 Il benessere fisico \u00e8 curato.<\/p>\n\n\n\n<p>I co-espositori saranno presenti con offerte interessanti.<\/p>\n\n\n\n<p>\ud83d\ude97 Parcheggi: Am Rackerschlag 1-7 e nella zona industriale<\/p>\n\n\n\n<p>\ud83d\udc49 Per saperne di pi\u00f9: www.wohnmobile-ratzeburg.de<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Nota di Eura Mobil: L'immagine \u00e8 solo a scopo illustrativo ed \u00e8 stata creata con l'aiuto dell'IA generativa. <\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Fr\u00fchlingsfest bei WOHNMOBILE RATZEBURG \u2013 Saisonstart 2026 \ud83d\udcc5 14. &amp; 15. M\u00e4rz 2026\u23f0 10\u201316 Uhr\ud83d\udccd An der Tongrube 4\u20136, 23909 Ratzeburg Zum Start in die Campingsaison 2026 l\u00e4dt WOHNMOBILE RATZEBURG (AL-CAR Technology) zum Fr\u00fchlingsfest ein. Besucher erwartet eine der gr\u00f6\u00dften Wohnmobil-Ausstellungen der Region mit rund 200 Fahrzeugen. \ud83d\udd39 Gro\u00dfe Auswahl an Wohnmobilen &amp; Reisevans\ud83d\udd39 bis [&hellip;]<\/p>\n","protected":false},"featured_media":22815,"template":"","meta":{"_acf_changed":true,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"class_list":["post-22810","events","type-events","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/it\/wp-json\/wp\/v2\/events\/22810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/it\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/it\/wp-json\/wp\/v2\/types\/events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/it\/wp-json\/wp\/v2\/media\/22815"}],"wp:attachment":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/it\/wp-json\/wp\/v2\/media?parent=22810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}