{"id":22667,"date":"2025-10-10T12:06:54","date_gmt":"2025-10-10T12:06:54","guid":{"rendered":"https:\/\/euramobil-25.tiw-01.mxp.services\/?post_type=events&#038;p=22667"},"modified":"2026-03-31T08:09:31","modified_gmt":"2026-03-31T08:09:31","slug":"invigningsceremoni-doerr-pfalz-ny-anlaeggning-i-hochdorf-assenheim","status":"publish","type":"events","link":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/events\/eroeffnungsfeier-doerr-pfalz-neuer-standort-in-hochdorf-assenheim\/","title":{"rendered":"Invigningsceremoni D\u00f6rr Pfalz - Ny anl\u00e4ggning i Hochdorf-Assenheim"},"content":{"rendered":"<p>Nu \u00e4r det \u00e4ntligen dags - vi \u00f6ppnar v\u00e5r nya D\u00f6rr Pfalz-filial och vill g\u00e4rna fira detta speciella \u00f6gonblick tillsammans med dig!<br>\u2728 Ser fram emot:<br>\ud83d\ude90 Exklusiva \u00f6ppningserbjudanden p\u00e5 v\u00e5ra husbilar<br>\ud83e\udd68 L\u00e4cker mat och uppfriskande drycker<br>\ud83c\udfb6 Bra st\u00e4mning och m\u00f6jlighet att l\u00e4ra k\u00e4nna v\u00e5rt team och den nya arbetsplatsen<br>Kom, ta med v\u00e4nner och familj och h\u00f6j ett glas med oss f\u00f6r framtiden f\u00f6r D\u00f6rr Pfalz i Hochdorf-Assenheim!<\/p>","protected":false},"excerpt":{"rendered":"<p>Endlich ist es soweit \u2013 wir er\u00f6ffnen unsere neue Filiale D\u00f6rr Pfalz und m\u00f6chten diesen besonderen Moment gemeinsam mit euch feiern!\u2728 Freut euch auf:\ud83d\ude90 Exklusive Er\u00f6ffnungsangebote auf unsere Reisemobile\ud83e\udd68 Leckeres Essen &amp; erfrischende Getr\u00e4nke\ud83c\udfb6 Gute Stimmung und Gelegenheit, unser Team und den neuen Standort kennenzulernenKommt vorbei, bringt Freunde &amp; Familie mit und sto\u00dft mit uns [&hellip;]<\/p>\n","protected":false},"featured_media":22671,"template":"","meta":{"_acf_changed":true,"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":""},"class_list":["post-22667","events","type-events","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/events\/22667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/types\/events"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/media\/22671"}],"wp:attachment":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/media?parent=22667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}