{"id":308,"date":"2019-03-29T11:57:33","date_gmt":"2019-03-29T11:57:33","guid":{"rendered":"https:\/\/euramobil-25.tiw-01.mxp.services\/?p=308"},"modified":"2025-08-05T15:05:25","modified_gmt":"2025-08-05T15:05:25","slug":"intervju-med-det-vaelsignade-paret-eura-mobil-the-beginnings","status":"publish","type":"post","link":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/interview-mit-ehepaar-blessing-eura-mobil-die-anfaenge\/","title":{"rendered":"Intervju med makarna Blessing: Eura Mobil - b\u00f6rjan"},"content":{"rendered":"\n<p><em>N\u00e4chstes Jahr feiert Eura Mobil sein 60-j\u00e4hriges Firmenjubil\u00e4um. Aus diesem Anlass haben wir ein Interview mit Anneliese und Heinz Blessing \u00fcber die Anf\u00e4nge unseres Unternehmens gef\u00fchrt. Nachfolgend der Artikel, der im Eura Mobil Kundenjournal im Januar 2019 erschienen ist.<\/em><\/p>\n\n\n\n<p><strong>Heinz Blessing<\/strong> ist der <strong>Gr\u00fcnder der Blessing Wohnwagenbau GmbH<\/strong>. Aus dieser Keimzelle der Caravan-Produktion in Sprendlingen nahe Bad Kreuznach ging die heutige <strong>Eura Mobil GmbH<\/strong> hervor. Bis 1969 leitete Heinz Blessing sein Unternehmen und zog sich dann aus gesundheitlichen Gr\u00fcnden zur\u00fcck. Seine Frau Anneliese engagierte sich ebenfalls fr\u00fch im Familienbetrieb und wurde anschlie\u00dfend Teilhaberin der Nachfolgegesellschaft Mayr KG, an der auch der sp\u00e4tere Eigent\u00fcmer der Eura Mobil GmbH Eugen Immler beteiligt war. Als stiller Teilhaber war sogar Erwin Hymer in der Mayr KG engagiert. Wir haben Heinz und Anneliese Blessing zu den Anf\u00e4ngen von Eura Mobil befragt.<\/p>\n\n\n\n<p><strong>Herr Blessing, was hat Sie 1959 bewogen, mit dem Bau von Wohnwagen zu beginnen?<\/strong><\/p>\n\n\n\n<p><strong>Heinz Blessing:<\/strong> Ich hatte immer den Traum, mit einem Wohnwagen zu verreisen und arbeitete mich, quasi als Hobby, in das Thema ein. Den ersten Wohnwagen aus Sperrholz baute ich in einem Anbau hinter unserem Haus. Aluminiumblech war zu dieser Zeit noch nicht verf\u00fcgbar. Beruflich war ich damals als studierter Elektro-Ingenieur viel mit der technischen Einrichtung f\u00fcr Kinos besch\u00e4ftigt. Als die Nachfrage im Kinomarkt nachlie\u00df, machte ich aus dem Hobby Wohnwagenbau einen Beruf, gr\u00fcndete 1959 die Blessing Wohnwagenbau GmbH und konstruierte mit einem befreundeten Schreiner mehrere Wohnwagen gleichzeitig, um Kosten zu sparen.<\/p>\n\n\n\n<p><strong>Was waren die Besonderheiten der ersten Blessing Wohnwagen? Was unterschied sie vom Wettbewerb?<\/strong><\/p>\n\n\n\n<p><strong>Heinz Blessing:<\/strong> Zun\u00e4chst bauten wir nur auf Sperrholzbasis, sp\u00e4ter dann verkleideten wird die Wohnwagen mit Aluminiumblech. Die Fenster waren uns wichtig, daher wurden gleich zu Beginn Doppel-Fenster verbaut. Anfangs die zweigeteilten, die damals auch beim VW Bus eingesetzt wurden, sp\u00e4ter dann gro\u00dfe einteilige Fenster. Zur Unterscheidung vom Wettbewerb hatte die Wohnwagen vorne und hinten eine \u201eNase\u201c, \u00fcber die das Regenwasser abflie\u00dfen konnte.<br><strong>Anneliese Blessing:<\/strong> Ich war f\u00fcr die Innenraumgestaltung verantwortlich. Polster, Gardinen, Deko. Alles, was mit Farben und Stoffen im Innenraum zu tun hatte, fiel in meinen Bereich. Wir haben beide anfangs auch bei der Produktion mitgearbeitet. Mein Mann packte zum Beispiel beim Lackieren selber mit an.<\/p>\n\n\n\n<p><strong>Gab es auch Schwierigkeiten am Anfang, die Sie \u00fcberwinden mussten?<\/strong><\/p>\n\n\n\n<p><strong>Heinz Blessing:<\/strong> Zum einen galt es, geeignete Produktionsr\u00e4ume f\u00fcr die Serienfertigung zu finden. Es lief so gut an, dass die Produktionsfl\u00e4che im Anbau hinter unserem Haus nicht mehr reichte. Auch die Erweiterung in der Friedrich-Ebert Stra\u00dfe wurde schnell zu klein. Es folgte eine Au\u00dfenstelle in Pfaffen-Schwabenheim, bevor es 1965 zum Neubau in der Kreuznacher Stra\u00dfe kam.<br><strong>Anneliese Blessing:<\/strong> Und dann mussten wir noch unser Logo ver\u00e4ndern. Wir hatten eine sch\u00f6ne Kompassrose in die Mitte eines Dreiecks gesetzt und mit roten Farbakzenten gestaltet. Das gefiel uns und den Kunden sehr gut. Aber Mercedes Benz hat dagegen Einspruch erhoben. Dabei ist die Kompassrose ein vierzackiger Stern. Wegen der vier Himmelsrichtungen. Der Mercedes Stern ist aber nur ein dreizackiger Stern. Das half aber nichts. Das erste Logo musste weg.<\/p>\n\n\n\n<p><strong>Wie entwickelte sich der Absatz in den ersten Jahren?<\/strong><\/p>\n\n\n\n<p><strong>Heinz Blessing:<\/strong> Wie viele Wohnwagen wir im ersten Jahr verkauft haben, wei\u00df ich nicht mehr. Pro Jahr m\u00f6gen es in den ersten zwei Jahren wohl so circa 200 St\u00fcck gewesen sein. Die K\u00e4ufer fanden wir zun\u00e4chst haupts\u00e4chlich auf Messen in Essen, der IAA in Frankfurt, dem Caravan Salon in Genf und Lausanne. Sp\u00e4ter kam dann ein H\u00e4ndlernetz im In- und Ausland hinzu. 1963 waren wir mit einem Titelbild auf der \u201eQuick\u201c [damals w\u00f6chentlich 1,7 Millionen Auflage Anm. der Red.]. Danach gingen die Verk\u00e4ufe sprunghaft nach oben. Ende der 60er Jahre stand die Firma gut da.<\/p>\n\n\n\n<p><strong>Wie hat sich die Modellpalette entwickelt?<\/strong><\/p>\n\n\n\n<p><strong>Heinz Blessing:<\/strong> 1960 hatten wir zwei Modelle im Programm: Den Merkur mit 3,00 Meter Aufbaul\u00e4nge und den Saturn mit 3,80 Meter Aufbaul\u00e4nge. Diese wurden mit verschiedenen Grundrissen zu Baureihen erweitert. 1963 haben wir schon zwei Merkur- und drei Saturn-Grundrisse angeboten. Also f\u00fcnf Modelle. 1965 waren es schon acht Modelle: Der 3 Meter kurze Mars, zwei Merkur- und drei Saturn-Grundrisse und zwei 4,50 Meter lange Jupiter-Grundrisse. Mit 50 Mitarbeitern, darunter Schreiner, Polsterer, Lackierer und Karosseriebauer, bauten wir Ende der 60er schon 800 Wohnwagen pro Jahr. Die Wohnwagen wurden per Bahn vom Sprendlinger Bahnhof in 9er Einheiten zu den H\u00e4ndlern transportiert.<\/p>\n\n\n\n<p><strong>1969 sind Sie, Herr Blessing, aus gesundheitlichen Gr\u00fcnden aus der Firma ausgeschieden. Es wurde die Mayr KG gegr\u00fcndet, an der Sie, Frau Blessing, als Gesellschafterin beteiligt waren. Die Mayr KG nutzte dann erstmals den Markennamen Eura Caravan. K\u00f6nnen Sie uns erkl\u00e4ren, wie es zu dem Markennamen kam?<\/strong><\/p>\n\n\n\n<p><strong>Anneliese Blessing:<\/strong> Zun\u00e4chst wollten wir \u201eEuropa Carvan\u201c anmelden, das wurde aber abgelehnt, da die Firma eine zu \u201egeringe Bedeutung\u201c h\u00e4tte. Der Begriff \u201eEuro\u201c war schon gesch\u00fctzt. Also hatte mein Mann Heinz die Idee, Eura Caravan anzumelden. Eura steht seither f\u00fcr E= Erholung, U=Urlaub, R= Reisen, A= Ausspannen.<\/p>\n\n\n\n<p>Wir danken Ihnen f\u00fcr dieses Gespr\u00e4ch!<\/p>\n\n\n\n<p>Wollen Sie immer \u00fcber spannende Neuheiten aus dem Hause Eura Mobil informiert sein und fahren Sie bereits ein Eura Mobil? Dann beantragen Sie unsere Kundenkarte und Sie erhalten 2x pro Jahr kostenlos das Eura Mobil Journal mit aktuellen Neuheiten aus unserem Hause und der Branche. <strong><a href=\"https:\/\/euramobil-25.tiw-01.mxp.services\/eura-mobil-welt\/eura-mobil-entdecken\/eura-mobil-card\/eura-mobil-card-antrag\/\">Hier die Eura Mobil Card beantragen!<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>N\u00e4chstes Jahr feiert Eura Mobil sein 60-j\u00e4hriges Firmenjubil\u00e4um. Aus diesem Anlass haben wir ein Interview mit Anneliese und Heinz Blessing \u00fcber die Anf\u00e4nge unseres Unternehmens gef\u00fchrt. Nachfolgend der Artikel, der im Eura Mobil Kundenjournal im Januar 2019 erschienen ist. Heinz Blessing ist der Gr\u00fcnder der Blessing Wohnwagenbau GmbH. Aus dieser Keimzelle der Caravan-Produktion in Sprendlingen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5266,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[11,52],"tags":[],"class_list":["post-308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-11","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/posts\/308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/comments?post=308"}],"version-history":[{"count":2,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/posts\/308\/revisions"}],"predecessor-version":[{"id":22408,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/posts\/308\/revisions\/22408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/media\/5266"}],"wp:attachment":[{"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/media?parent=308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/categories?post=308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euramobil-25.tiw-01.mxp.services\/sv\/wp-json\/wp\/v2\/tags?post=308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}